{"id":6183,"date":"2021-10-18T12:14:09","date_gmt":"2021-10-18T15:14:09","guid":{"rendered":"https:\/\/hcdvillademerlo.com\/?p=6183"},"modified":"2024-09-24T10:06:10","modified_gmt":"2024-09-24T13:06:10","slug":"ordenanza-n-viii-1005-hcd-2021","status":"publish","type":"post","link":"https:\/\/hcdvillademerlo.com\/index.php\/2021\/10\/18\/ordenanza-n-viii-1005-hcd-2021\/","title":{"rendered":"ORDENANZA N\u00b0 VIII-1005-HCD-2021 &#8211; DEROGA INC. D 917"},"content":{"rendered":"\n<p>Villa de Merlo, (San Luis), 16 de Septiembre de 2021.-<\/p>\n\n\n\n<p>ORDENANZA N\u00b0 VIII-1005-HCD-2021<\/p>\n\n\n\n<p>VISTO:<\/p>\n\n\n\n<p>La solicitud formulada por la Secretar\u00eda de Gobierno y Desarrollo Social y Coordinaci\u00f3n de la Municipalidad Villa de Merlo formulado mediante la Nota Recibida N\u00b0 247-HCD-2021, ingresada con fecha 08.09.2021; y:<\/p>\n\n\n\n<p>CONSIDERANDO:<\/p>\n\n\n\n<p>Que el pedido consiste en elevar nota de la Secretar\u00eda de Gesti\u00f3n Ambiental y Desarrollo Sustentable del Municipio, la que solicita se derogue el Inciso \u201cd\u201d del Art\u00edculo 9\u00b0 de la Ordenanza N\u00b0 917-HCD-2005, el que establece: \u201cArt. 9\u00b0\u2026 d)- Para los I.I.A. o E.I.A., en caso de proyectos presentados por privados para ser ejecutados dentro de su propiedad, deber\u00e1 expedirse en un t\u00e9rmino m\u00e1ximo de cuarenta y cinco (45) d\u00edas corridos contados a partir de la presentaci\u00f3n de los mismos, pudi\u00e9ndose extender el plazo en caso de consulta a organismos t\u00e9cnicos provinciales o nacionales, descontando el t\u00e9rmino de la consulta. Vencido dicho plazo sin que se hubiere expedido, se considerar\u00e1n las exigencias del presente cumplidas\u201d&#8230;-<\/p>\n\n\n\n<p>Que fundamentan el pedido en el hecho de que la evaluaci\u00f3n de dichos estudios puede superar ese tiempo seg\u00fan la complejidad de los mismos y requerir documentaci\u00f3n respaldatoria cuya presentaci\u00f3n casi siempre supera los plazos indicados.-<\/p>\n\n\n\n<p>Que informan tambi\u00e9n que se ha conformado la Comisi\u00f3n Evaluadora Municipal conformada por un referente de la Secretar\u00eda de Ordenamiento Territorial, un referente de la Secretar\u00eda de Gesti\u00f3n Ambiental y la propia Responsable de \u00e9sta \u00faltima.-<\/p>\n\n\n\n<p>Que la Comisi\u00f3n de Planeamiento y Ambiente actual del H.C.D. elev\u00f3 sus conclusiones al Plenario del Cuerpo, el que dispone hacer lugar a lo solicitado y consecuentemente dictar la presente Ordenanza en los siguientes t\u00e9rminos.-<\/p>\n\n\n\n<p>Que por todo ello se dispone conforme a continuaci\u00f3n se establece.-<\/p>\n\n\n\n<p>POR TODO LO EXPUESTO, ESTE HONORABLE CONCEJO DELIBERANTE DE LA CIUDAD VILLA DE MERLO, SAN LUIS, EN USO DE LAS ATRIBUCIONES Y FACULTADES QUE LE CONFIERE LA LEY SANCIONA LA SIGUIENTE:<\/p>\n\n\n\n<p>ORDENANZA<\/p>\n\n\n\n<p>ARTICULO 1\u00ba: DEROGAR, por las razones que anteceden en los considerandos de la presente norma, el Inciso \u201cd\u201d, del Art\u00edculo 9\u00b0, de la Ordenanza N\u00b0 917-HCD-2005, sancionada con fecha 15 de Junio de 2005.-<\/p>\n\n\n\n<p>ARTICULO 2\u00ba: COMUN\u00cdQUESE, REG\u00cdSTRESE, PUBL\u00cdQUESE Y OPORTUNAMENTE, ARCH\u00cdVESE. &#8211;<\/p>\n\n\n\n<div class=\"wp-block-file btn-descarga-ordenanza\"><a id=\"wp-block-file--media-f5a69cc2-49ef-49b8-9cb0-b69c43d473ab\" href=\"https:\/\/hcdvillademerlo.com\/wp-content\/uploads\/2021\/10\/1005-VIII-DEROGA-INC.-D-917.docx\" target=\"_blank\" rel=\"noreferrer noopener\">1005-VIII- DEROGA INC. D 917<\/a><a href=\"https:\/\/hcdvillademerlo.com\/wp-content\/uploads\/2021\/10\/1005-VIII-DEROGA-INC.-D-917.docx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f5a69cc2-49ef-49b8-9cb0-b69c43d473ab\"><i class=\"fa fa-download\"><\/i>Descargar ordenanza<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DEROGA INC. D 917<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,296,9],"tags":[],"class_list":["post-6183","post","type-post","status-publish","format-standard","hentry","category-ordenanza","category-ordenanzas-2021","category-planeamiento-urbano"],"_links":{"self":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/6183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/comments?post=6183"}],"version-history":[{"count":4,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/6183\/revisions"}],"predecessor-version":[{"id":10932,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/6183\/revisions\/10932"}],"wp:attachment":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/media?parent=6183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/categories?post=6183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/tags?post=6183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}