{"id":3225,"date":"2017-11-16T09:19:39","date_gmt":"2017-11-16T12:19:39","guid":{"rendered":"http:\/\/www.hcdvillademerlo.com.ar\/?p=3225"},"modified":"2017-11-16T09:19:39","modified_gmt":"2017-11-16T12:19:39","slug":"orden-del-dia-sesion-ordinaria-fecha-16-de-noviembre-de-2017-acta-n-036-hcd-2017","status":"publish","type":"post","link":"https:\/\/hcdvillademerlo.com\/index.php\/2017\/11\/16\/orden-del-dia-sesion-ordinaria-fecha-16-de-noviembre-de-2017-acta-n-036-hcd-2017\/","title":{"rendered":"ORDEN DEL D\u00cdA &#8211; SESI\u00d3N ORDINARIA  FECHA: 16 DE NOVIEMBRE DE 2017:  ACTA N\u00b0 036-HCD-2017"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><u>ORDEN DEL D\u00cdA &#8211; SESI\u00d3N ORDINARIA<\/u><\/h2>\n<h2 style=\"text-align: center;\"><u>FECHA: 16 DE NOVIEMBRE DE 2017<\/u>:<\/h2>\n<h2 style=\"text-align: center;\"><u>ACTA N<\/u><u>\u00b0<\/u><u> 036-HCD-2017<\/u><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong><u>BANCA DEL VECINO:<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Sra. Yanina Z\u00e1rate<strong>, \u00a0<\/strong>para debatir temas relacionados al consumo de alcohol de menores de 18 a\u00f1os.-<\/p>\n<p style=\"text-align: justify;\"><strong><u>De las Actas<\/u>:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>1) Lectura y Aprobaci\u00f3n de Actas Anteriores.-<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Acta\u00a0 N\u00ba 034 del d\u00eda 02 de Noviembre\u00a0 de 2017&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p style=\"text-align: justify;\">Acta\u00a0 N\u00ba 035 del d\u00eda 09 de Noviembre\u00a0 de 2017&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><u>De los Despachos de Comisi\u00f3n.-<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>2) Nota R.<\/strong><strong> N\u00ba 780-HCD-17.- <\/strong>Despacho de Comisi\u00f3n, Proyecto de Resoluci\u00f3n, en ref.: AUTORIZAR, la DEMOLICION de la propiedad del Sr. EDUARDO PEREZ, conocida como \u201cTALLER DE EDUARDO PEREZ\u201d, cuyos propietarios en la actualidad son los Sres. SERGIO ESTEBAN PEREZ, GUILLERMO ERNESTO PEREZ, VERONICA BEATRIZ PEREZ y GUSTAVO EDUARDO PEREZ, sito en Calle Janzon esquina Poeta Ag\u00fcero de esta Villa.-<\/p>\n<p style=\"text-align: justify;\"><strong>3) Nota R.<\/strong><strong> N\u00ba 781-HCD-17.- <\/strong>Despacho de Comisi\u00f3n, Proyecto de Resoluci\u00f3n, en ref.: DECLARAR DE INTERES CULTURAL MUNICIPAL, a \u201cRadio Alternativa\u201d, 99.3 Mhz,\u00a0 al cumplirse 30 a\u00f1os de la existencia de este medio.-<\/p>\n<p style=\"text-align: justify;\"><strong>4) Nota R.<\/strong><strong> N\u00ba 783-HCD-17.- <\/strong>Despacho de Comisi\u00f3n:<\/p>\n<p>a) Proyecto de Nota al Secretario de Gesti\u00f3n Territorial. Arq. Nicol\u00e1s Rosatti, en ref.: solicitar relevamiento de inmueble por Expte. de los Sres. Marveggio, Nelly y otros.<br \/>\nb) Proyecto de Nota a la Juez de Faltas Municipal, Dra. Emilia Zu\u00e1zquita, en ref.: informarle existencia y tratamiento dado, sobre Expte. de los Sres. Marveggio, Nelly y otros, por solicitud de subdivisi\u00f3n de Propiedad.-<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><u>De las Comunicaciones Oficiales.-<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>5) Nota R.<\/strong><strong> N\u00ba 771-HCD-17.- <\/strong>Escuela T\u00e9cnica 34 \u201cAr\u00edstides Bratti\u201d, invita a participar de las 4\u00ba Jornadas de Puertas Abiertas, a realizarse los d\u00edas jueves 16 y viernes 17.-<\/p>\n<p style=\"text-align: justify;\"><strong>6) Nota R.<\/strong><strong> N\u00ba 773-HCD-17.- <\/strong>Escuela N\u00ba 181 \u201cSan Jos\u00e9 de Calasanz\u201d de Piedra Blanca Arriba, invita a la Fiesta de la Tradici\u00f3n y la Familia, a realizarse el d\u00eda viernes 17-11, a partir de las\u00a0 19hs.-<\/p>\n<p style=\"text-align: justify;\"><strong>7) Nota R.<\/strong><strong> N\u00ba 778-HCD-17.- <\/strong>Poder Judicial de San Luis, eleva Oficio PEX 217533\/17 \u201cAGENTE FISCAL S\/DENUNCIA INCUMPLIMIENTO ORDEN FUNCIONARIO P\u00daBLICO\u201d.-<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><u>De los Informes (y\/o solicitudes) del D.E.M..-<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>8) Nota R.<\/strong><strong> N\u00ba 768-HCD-17.- <\/strong>Secretario de Gesti\u00f3n Territorial, Arq. Nicol\u00e1s Rosatti y Secretario de Gobierno, Dr. Jos\u00e9 O P\u00e9rez \u00a0de la Municipalidad de la Villa de Merlo, elevan Documentaci\u00f3n presentada por el Sr. Jorge Eduardo Altamirano, el cu\u00e1l solicita instalar un m\u00e1stil de 42 Metros para\u00a0 Antenas de Radiodifusi\u00f3n Sonora\u00a0 por Modulaci\u00f3n de Frecuencia.-<\/p>\n<p style=\"text-align: justify;\"><strong>9) Nota R.<\/strong><strong> N\u00ba 775-HCD-17.-<\/strong> Secretario de Gesti\u00f3n Territorial de la Municipalidad de la Villa de Merlo, Arq. Nicol\u00e1s Rosatti, eleva convenio de donaci\u00f3n y copia de la mensura aprobada por la Direcci\u00f3n de Catastro Provincial, de un Espacio Verde ubicado en B\u00ba Rinc\u00f3n del Este, para homologar.-<\/p>\n<p style=\"text-align: justify;\"><strong>10) Nota R.<\/strong><strong> N\u00ba 776-HCD-17.- <\/strong>Secretario de Gesti\u00f3n Territorial de la Municipalidad de la Villa de Merlo, Arq. Nicol\u00e1s Rosatti, eleva convenio de donaci\u00f3n y copia de la mensura aprobada por la Direcci\u00f3n de Catastro Provincial, de un Espacio Verde ubicado en Cerro de Oro, para homologar.-<\/p>\n<p style=\"text-align: justify;\"><strong>11) Nota R.<\/strong><strong> N\u00ba 777-HCD-17.- <\/strong>Secretario de Gobierno de la Municipalidad de la Villa de Merlo, Dr. Jos\u00e9 Oscar P\u00e9rez y Secretario de Gesti\u00f3n Territorial, Arq. Nicol\u00e1s Rosatti, responden Nota E. N\u00ba 248-HCD-2017 y elevan listado de vecinos del denominado Loteo \u201cPellegrini\u201d Barrio El Pantanillo.-<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><u>De las Peticiones o Asuntos Particulares.-<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>12) Nota R.<\/strong><strong> N\u00ba 770-HCD-17.- <\/strong>Sr. Juan Sebasti\u00e1n Palomero y otros integrantes del Grupo Cultural llamado \u201cAnimerlo 2018\u201d, solicitan Declaraci\u00f3n de Inter\u00e9s \u00a0Cultural y Municipal para el pr\u00f3ximo evento, a realizarse el d\u00eda Domingo 21 de enero del a\u00f1o 2018, desde las 11 de la ma\u00f1ana hasta las 21:00 horas en la reserva El Viejo Molino.-<\/p>\n<p style=\"text-align: justify;\"><strong>13) Nota R. N\u00ba 772 -HCD-17.- <\/strong>Veterinarios \u00a0del Norte de San Luis,\u00a0 Sres. Carlos Serna e Isidro Ortega, solicitan apoyo y auspicio para la realizaci\u00f3n del \u201c1\u00ba Simposio de Sanidad Animal\u201d a realizarse el d\u00eda 25.11.17\u00a0 a las 8:30 hs. (lugar a confirmar) y tambi\u00e9n la posibilidad de Declaraci\u00f3n de Inter\u00e9s a dicho evento.-<\/p>\n<p style=\"text-align: justify;\"><strong>14) Nota R.<\/strong><strong> N\u00ba 774-HCD-17.-<\/strong> Sra. Lorena Paradzik, solicita se Declare de Inter\u00e9s Municipal el 3\u00ba Congreso Multidisciplinario denominado \u201cYoga es Uni\u00f3n\u201d \u00a0a realizarse\u00a0 los d\u00edas 18, 19 y 20 de Noviembre en \u00a0Piedra Blanca.-<\/p>\n<p style=\"text-align: justify;\"><strong>15) Nota R.<\/strong><strong> N\u00ba 779-HCD-17.- <\/strong>Regente de la Escuela N\u00ba 34 \u201cAr\u00edstides Bratti\u201d, Prof. Silvana Gim\u00e9nez, solicita se Declare de Inter\u00e9s\u00a0 Municipal\u00a0 la Cuarta Jornada de Puertas Abiertas, a realizarse los d\u00edas 16 y 17 de Noviembre en la Instituci\u00f3n y adjunta programa de actividades.-<\/p>\n<p style=\"text-align: justify;\"><strong>16) Nota R.<\/strong><strong> N\u00ba 782-HCD-17.- <\/strong>Sra. M\u00f3nica Cinthia Krempovich, solicita reuni\u00f3n de comisi\u00f3n para exponer mejoras en la Ordenanza, junto con el proyecto \u201cPrueba Piloto\u201d, ya presentado al HCD.-<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; ORDEN DEL D\u00cdA &#8211; SESI\u00d3N ORDINARIA FECHA: 16 DE NOVIEMBRE DE 2017: ACTA N\u00b0 036-HCD-2017 &nbsp; BANCA DEL VECINO: Sra. Yanina Z\u00e1rate, \u00a0para debatir temas relacionados al consumo de alcohol de menores de 18 a\u00f1os.- De las Actas: 1) Lectura y Aprobaci\u00f3n de Actas Anteriores.- Acta\u00a0 N\u00ba 034 del d\u00eda 02 de Noviembre\u00a0 de<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/hcdvillademerlo.com\/index.php\/2017\/11\/16\/orden-del-dia-sesion-ordinaria-fecha-16-de-noviembre-de-2017-acta-n-036-hcd-2017\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3225","post","type-post","status-publish","format-standard","hentry","category-orden-del-dia"],"_links":{"self":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/3225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3225"}],"version-history":[{"count":0,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/3225\/revisions"}],"wp:attachment":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}