{"id":1637,"date":"2016-05-23T09:28:51","date_gmt":"2016-05-23T12:28:51","guid":{"rendered":"http:\/\/hcdvillademerlo.com.ar.j8a.com.ar\/?p=1637"},"modified":"2021-11-23T22:20:21","modified_gmt":"2021-11-24T01:20:21","slug":"crea-oficina-del-registro-municipal-de-vehiculos-cuatriciclos-de-la-villa-de-merlo","status":"publish","type":"post","link":"https:\/\/hcdvillademerlo.com\/index.php\/2016\/05\/23\/crea-oficina-del-registro-municipal-de-vehiculos-cuatriciclos-de-la-villa-de-merlo\/","title":{"rendered":"CREA OFICINA DEL REGISTRO MUNICIPAL DE VEH\u00cdCULOS CUATRICICLOS DE LA VILLA DE MERLO"},"content":{"rendered":"<p style=\"text-align: right\">Villa de Merlo, San Luis 06 de junio de 2012<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong><u>ORDENANZA N\u00ba \u00a0IV-0482-HCD-2012<\/u><\/strong><\/p>\n<p>&nbsp;<br \/>\n<strong><u>VISTO:<\/u><\/strong><br \/>\nLa necesidad de contar con normativa espec\u00edfica que regule las condiciones y los permisos de circulaci\u00f3n para veh\u00edculos motorizados denominados \u201ccuatriciclos\u201d, y:<br \/>\n<strong><u>CONSIDERANDO:<\/u><\/strong><\/p>\n<p style=\"text-align: justify\">Que, en algunos casos, estos veh\u00edculos salidos de f\u00e1brica no poseen los accesorios imprescindibles para la circulaci\u00f3n por la v\u00eda p\u00fablica, estimando necesaria su adecuaci\u00f3n cumpliendo ciertos requisitos de seguridad seg\u00fan lo establecen el Art. 29\u00ba de la Ley Nacional de Tr\u00e1nsito y Seguridad Vial\u00a0 N\u00ba 24.449 y el Art. 29 de la Ley Provincial de Tr\u00e1nsito y Seguridad Vial N\u00ba\u00a0X-0630-2008. Tal normativa debe tender al resguardo y protecci\u00f3n del usuario, cuyas especiales caracter\u00edsticas requieren una debida atenci\u00f3n por parte del Municipio.-<\/p>\n<p style=\"text-align: justify\">Que esto sucede en un contexto de crecimiento sin precedentes en la venta de estos veh\u00edculos, dado que la moda y la popularizaci\u00f3n de los precios hizo que se difundieran enormemente.-<\/p>\n<p style=\"text-align: justify\">Que anteriormente los cuatriciclos eran rodados reservados, para algunas tareas rurales o de competici\u00f3n muy alejadas del pavimento y zonas urbanas y\u00a0 residenciales, donde no hay normativa espec\u00edfica que lo regule.-<\/p>\n<p style=\"text-align: justify\">Que existe una tendencia importante a nivel mundial para el uso de este tipo de veh\u00edculos para el desplazamiento, integraci\u00f3n y acceso de personas con discapacidades motrices a medios de transporte efectivos y \u00fatiles, tendencia que se observa tambi\u00e9n en nuestro pa\u00eds.-<\/p>\n<p style=\"text-align: justify\">Que dichos veh\u00edculos se deben adecuar a las normas vigentes de la Ley de Tr\u00e1nsito, acompa\u00f1ando el crecimiento de nuestra localidad.-<\/p>\n<p style=\"text-align: justify\">Que por Ordenanza N\u00ba IV-0310-HCD-2011 (<strong>0468<\/strong>), la Municipalidad de Villa de Merlo adhiere a la Ley de Tr\u00e1nsito y Seguridad Vial de la Provincia de San Lu\u00eds.-<\/p>\n<p style=\"text-align: justify\">Que al carecerse de una disposici\u00f3n espec\u00edfica respecto a la tipolog\u00eda de los cuatriciclos, debido a que la Ley Nacional de Tr\u00e1nsito N\u00ba 24.449 precede la introducci\u00f3n y comercializaci\u00f3n de este tipo de veh\u00edculos en el pa\u00eds, bien puede encuadrarse dentro del Art.5\u00b0, Inc. X, de la misma Ley, que define como veh\u00edculo automotor a \u201c<em>todo veh\u00edculo de m\u00e1s de dos ruedas con motor y tracci\u00f3n propias<\/em>\u201d.-<\/p>\n<p style=\"text-align: justify\">Que, ante la existencia en el distrito de rodados de estas caracter\u00edsticas en buen n\u00famero, es atendible permitir su utilizaci\u00f3n bajo las disposiciones emanadas en la presente Ordenanza y en las normativas Nacionales y Provinciales.-<\/p>\n<p style=\"text-align: justify\">Que tanto el Art.2\u00ba de la Ley Nacional de Tr\u00e1nsito N\u00ba 24.449, como el Art. 2\u00ba de la Ley Provincial de Tr\u00e1nsito N\u00ba\u00a0<strong>X-0630-2008, <\/strong>establecen \u201cque los Municipios son autoridad de aplicaci\u00f3n y que \u201c<em>podr\u00e1n dictar tambi\u00e9n normas exclusivas, siempre que sean accesorias a las de esta Ley y se refieran al tr\u00e1nsito y estacionamiento urbano, al ordenamiento de la circulaci\u00f3n de veh\u00edculos<\/em>\u201d.-<\/p>\n<p style=\"text-align: justify\">Que tanto el Art.11\u00b0 de la Ley Nacional de Tr\u00e1nsito N\u00ba 24.449, como el Art.11\u00b0 de la Ley Provincial de Tr\u00e1nsito N\u00ba X-0630-2008, en su \u00faltimo p\u00e1rrafo expresan \u201c<em>las autoridades jurisdiccionales pueden establecer en raz\u00f3n de fundadas caracter\u00edsticas locales, excepciones a las edades m\u00ednimas para conducir, las que solo ser\u00e1n v\u00e1lidas con relaci\u00f3n al tipo de veh\u00edculo y a las zonas que determinen en el \u00e1mbito de su jurisdicci\u00f3n<\/em>\u201d.-<\/p>\n<p style=\"text-align: justify\">Que si tenemos en cuenta que con 17 a\u00f1os de edad y con la autorizaci\u00f3n del tutor, se puede obtener la Licencia de Conductor que habilita para conducir veh\u00edculos automotores de dimensiones y peso, muy superiores a los de un \u201ccuatriciclo\u201d, los que adem\u00e1s pueden desarrollar mayor velocidad, aumentando as\u00ed considerablemente la posibilidad accidentes, dado que est\u00e1n autorizados para transitar por toda la Rep\u00fablica Argentina.-<\/p>\n<p style=\"text-align: justify\">Que resulta controvertido que el Registro Nacional de la Propiedad del Automotor, al momento de tramitar la registraci\u00f3n de veh\u00edculos denominados\u00a0 \u201ccuatriciclos\u201d\u00a0 hace entrega \u00fanicamente del T\u00edtulo de Propiedad\u00a0 y lo denomina \u201cTitulo del Motoveh\u00edculo\u201d y retiene las matriculas del dominio (patentes), y la tarjeta de identificaci\u00f3n de la unidad (tarjeta verde), documentaci\u00f3n que resulta imprescindible al momento de transitar, no procediendo de igual forma con los dem\u00e1s motoveh\u00edculos que inscribe.-<\/p>\n<p style=\"text-align: justify\">Que la Direcci\u00f3n Provincial de Ingresos P\u00fablicos considera al Titular del veh\u00edculo \u201ccuatriciclo\u201d como contribuyente y le aplica un impuesto que lo denomina\u00a0 \u201cimpuesto b\u00e1sico de motos\u201d pero no puede utilizar las calles y rutas por donde si pueden hacerlo otro tipo de motoveh\u00edculos.-<\/p>\n<p style=\"text-align: justify\">Que la Ordenanza N\u00ba IV-0034-HCD-1998 (<strong>703<\/strong>) vigente, reglamenta la actividad comercial de alquiler de cuatriciclos y areneros, pero no as\u00ed su circulaci\u00f3n en la v\u00eda p\u00fablica.-<\/p>\n<p style=\"text-align: justify\">Que para su circulaci\u00f3n y el debido control resulta adecuado dotar del marco legal necesario a quienes act\u00faan con el poder de polic\u00eda en el \u00e1mbito municipal, adem\u00e1s de reglamentar su estacionamiento y circulaci\u00f3n en el ejido urbano de Villa de Merlo.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>POR TODO ELLO EL HONORABLE CONCEJO DELIBERANTE DE LA CIUDAD\u00a0 VILLA DE MERLO, SAN LUIS, EN USO DE LAS FACULTADES Y ATRIBUCIONES QUE LE CONFIERE LA LEY, SANCIONA LA SIGUIENTE:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong><u>O R D E N A N Z A<\/u><\/strong><\/p>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.1\u00ba) CR\u00c9ASE la OFICINA DEL REGISTRO MUNICIPAL DE VEH\u00cdCULOS CUATRICICLOS DE LA VILLA DE MERLO,<\/strong> que ser\u00e1 el encargado de inscribirlos y matricularlos, para posibilitar su circulaci\u00f3n dentro del ejido municipal.-<\/p>\n<p style=\"text-align: justify\">La autoridad de aplicaci\u00f3n ser\u00e1 la Direcci\u00f3n de Tr\u00e1nsito de la Municipalidad, quien ser\u00e1 la encargada de crear dicho Registro.-<\/p>\n<p style=\"text-align: justify\">Ser\u00e1 esa dependencia, quien proveer\u00e1 al titular de ese tipo de unidad, una vez presentada la documentaci\u00f3n que acredite su registraci\u00f3n a nivel nacional, de un juego de dos placas met\u00e1licas rectangulares id\u00e9nticas, cuya dimensi\u00f3n ser\u00e1 de 20 cm. x 15 cm., pintadas en su fondo de color rojo, tendr\u00e1 una letra y tres n\u00fameros estampados en relieve de 6 cm. de alto y 3 cm de ancho, separados entre s\u00ed por 1 cm., pintados de color blanco, y en el margen inferior la leyenda \u201cMunicipalidad de Villa de Merlo\u201d pintados de color blanco.-<\/p>\n<p style=\"text-align: justify\">Ante cualquier transferencia de dominio el titular deber\u00e1 presentar la documentaci\u00f3n nacional correspondiente.-<\/p>\n<p style=\"text-align: justify\">Para poder circular dentro del ejido, el titular o quien \u00e9l designe, se encargar\u00e1n de colocar las placas en la parte delantera y trasera del veh\u00edculo, de manera visible para su r\u00e1pida identificaci\u00f3n.-<\/p>\n<p style=\"text-align: justify\">En el mismo acto y en ambos casos, se har\u00e1 entrega al titular, de una tarjeta plastificada de circulaci\u00f3n que contenga todos sus datos personales como as\u00ed tambi\u00e9n los datos del veh\u00edculo. Su portaci\u00f3n ser\u00e1 obligatoria para poder circular y podr\u00e1 ser exigido por las autoridades de tr\u00e1nsito en los controles que \u00e9stos efect\u00faen, cuando as\u00ed lo requieran.-<\/p>\n<p style=\"text-align: justify\">A su solicitud el titular podr\u00e1 obtener extensiones de tarjetas de circulaci\u00f3n para las personas que designe y que cumplan con los requisitos exigidos por la Direcci\u00f3n de Tr\u00e1nsito Municipal en consonancia con las Leyes Nacionales y provinciales vigentes. La falta de este documento har\u00e1 pasible al conductor y al titular, de las sanciones correspondientes.<\/p>\n<p style=\"text-align: justify\">La tramitaci\u00f3n de las placas identificatorias, de la tarjeta de circulaci\u00f3n y sus extensiones, podr\u00e1 ser realizada \u00fanicamente por el titular del veh\u00edculo.-<\/p>\n<p style=\"text-align: justify\">El costo de las placas y la tarjeta del titular ser\u00e1 el equivalente de hasta SETENTA (70) unidades de valor de nafta s\u00faper de mayor octanaje, en tanto que las extensiones de tarjetas que pudiere solicitar tendr\u00e1n un costo de CINCO (5) unidades de valor cada una. Frente al extrav\u00edo deber\u00e1n abonarse nuevamente los montos establecidos en la presente.-<\/p>\n<p style=\"text-align: justify\">\u00a0La obtenci\u00f3n de placas y tarjetas queda supeditada al cumplimiento de las disposiciones de los art\u00edculos subsiguientes.-<\/p>\n<p style=\"text-align: justify\">Para el caso que el veh\u00edculo sea vendido y\/o transferido, el titular que se encontrare registrado, deber\u00e1 dar aviso en forma inmediata de la novedad al Registro Municipal, lo que lo liberar\u00e1 de la responsabilidad, ante posibles futuras infracciones.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.2\u00ba) PERM\u00cdTASE<\/strong> en la ciudad Villa de Merlo la circulaci\u00f3n de los veh\u00edculos ligeros, de cuatro ruedas, con manubrio, asiento del tipo de monociclos y mecanismo de cambio de velocidades, con o sin marcha atr\u00e1s, para el transporte de personas, con o sin dispositivo de enganche para remolque, con motor el\u00e9ctrico o a combusti\u00f3n interna superior a los 70 cm3, fabricados en serie, denominados cuatriciclos.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.3\u00ba) PROH\u00cdBASE<\/strong> la circulaci\u00f3n en la v\u00eda p\u00fablica de los modelos infantiles no matriculables, los cuales no son considerados por esta normativa, por lo que su uso est\u00e1 restringido a lugares privados o circuitos cerrados al tr\u00e1nsito.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.4\u00ba)<\/strong> Las disposiciones de la presente Ordenanza son aplicables a toda persona, con o sin residencia en el Distrito de Villa de Merlo, aunque el rodado haya sido matriculado, registrado, patentado o autorizado en otra jurisdicci\u00f3n.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.5\u00ba) ESTABL\u00c9CENSE<\/strong> las siguientes disposiciones para la circulaci\u00f3n de cuatriciclos:<\/p>\n<ul>\n<li style=\"text-align: justify\">\u00a0El conductor deber\u00e1 ser mayor de 17 a\u00f1os con autorizaci\u00f3n del tutor y poseer licencia de conductor clase A3;<\/li>\n<li style=\"text-align: justify\">\u00a0La cantidad m\u00e1xima de ocupantes ser\u00e1 la que figure en la homologaci\u00f3n de f\u00e1brica del rodado;<\/li>\n<li style=\"text-align: justify\">\u00a0El veh\u00edculo deber\u00e1 estar equipado con: luces de posici\u00f3n, farol delantero con luz baja y alta de color blanco o amarillo, luces de giros intermitentes, luz para la patente trasera, luz de frenado de color rojo, espejos retrovisores, bocina, los conductores y acompa\u00f1antes tendr\u00e1n que llevar el casco reglamentario, anteojos de seguridad, freno de estacionamiento, Y contar con Verificaci\u00f3n t\u00e9cnica municipal obligatoria a partir de su implementaci\u00f3n;<\/li>\n<li style=\"text-align: justify\">\u00a0La velocidad m\u00e1xima en calles urbanas y avenidas nunca podr\u00e1 ser superior a 40 Km\/h, reduci\u00e9ndose dicho l\u00edmite a 20 Km\/h en los cruces de calles. En proximidad de establecimientos escolares, deportivos y\/o de gran afluencia de personas, la velocidad nunca podr\u00e1 ser superior a 20 Km\/h.<\/li>\n<li style=\"text-align: justify\">\u00a0Deber\u00e1n circular por la calzada, sobre la derecha, no pudiendo circular a la par uno de otro, evitando maniobras zigzagueantes, sinuosas o sin el apoyo de todas sus ruedas en la calle, intempestivas, de modo que se genere un peligro para s\u00ed y para terceras personas;<\/li>\n<li style=\"text-align: justify\">\u00a0Todo conductor inexorablemente deber\u00e1 poseer licencia de conducir, seguro de responsabilidad civil contra terceros, tarjeta de circulaci\u00f3n y placa identificatoria otorgada por el municipio;<\/li>\n<li style=\"text-align: justify\">\u00a0Se encuentra absolutamente prohibido circular con cuatriciclos que emitan gases, humos, ruidos, radiaciones u otras emanaciones contaminantes del ambiente que excedan los l\u00edmites de tolerancia normal. A tal fin, cada veh\u00edculo deber\u00e1 estar provisto de su aparato silenciador o amortiguador de gases y ruidos.-<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.6\u00ba)<\/strong> El estacionamiento de estos veh\u00edculos s\u00f3lo se permitir\u00e1 en los espacios destinados a las motocicletas.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.7\u00ba)<\/strong> Las infracciones a las Leyes de Tr\u00e1nsito vigentes, a la presente Ordenanza y las reglamentaciones que con posterioridad se dicten y el incumplimiento a las intimaciones y emplazamientos que se practiquen, como asimismo la omisi\u00f3n o falseamiento de los datos e informaciones que se requieran, dar\u00e1n lugar a la aplicaci\u00f3n de sanciones\u00a0 o multas en vigencia, equivalentes a las previstas para motocicletas, conforme al C\u00f3digo Municipal de Faltas.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.8\u00ba)<\/strong> Para su circulaci\u00f3n, los cuatriciclos destinados a paseos y\/o excursiones, deber\u00e1n ajustarse a las disposiciones de la presente Ordenanza, a los cuales se les har\u00e1 entrega de una identificaci\u00f3n que los distinga de los veh\u00edculos particulares, sin perjuicio del cumplimiento de las Ordenanzas y reglamentaciones vigentes o que se dicten en el futuro, para el alquiler de este tipo de rodados.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.9\u00ba) ESTABL\u00c9ZCASE<\/strong> el plazo de SEIS (6) meses, a partir de la reglamentaci\u00f3n de la presente para la adecuaci\u00f3n de los veh\u00edculos, de acuerdo a los requisitos para la circulaci\u00f3n, previstos en esta Ordenanza.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.10\u00ba)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 INCORP\u00d3RESE<\/strong> a la categor\u00eda A3 de los registros de conducir expedidos por la Direcci\u00f3n Municipal de Tr\u00e1nsito, la denominaci\u00f3n \u201ccuatriciclos\u201d.-<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Art.11\u00ba)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 COMUN\u00cdQUESE, REG\u00cdSTRESE, PUBL\u00cdQUESE Y OPORTUNAMENTE, ARCH\u00cdVESE.-<\/strong><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villa de Merlo, San Luis 06 de junio de 2012 &nbsp; ORDENANZA N\u00ba \u00a0IV-0482-HCD-2012 &nbsp; VISTO: La necesidad de contar con normativa espec\u00edfica que regule las condiciones y los permisos de circulaci\u00f3n para veh\u00edculos motorizados denominados \u201ccuatriciclos\u201d, y: CONSIDERANDO: Que, en algunos casos, estos veh\u00edculos salidos de f\u00e1brica no poseen los accesorios imprescindibles para la<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/hcdvillademerlo.com\/index.php\/2016\/05\/23\/crea-oficina-del-registro-municipal-de-vehiculos-cuatriciclos-de-la-villa-de-merlo\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[300,16],"tags":[],"class_list":["post-1637","post","type-post","status-publish","format-standard","hentry","category-ordenanzas-2012","category-transporte"],"_links":{"self":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":1,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":6983,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions\/6983"}],"wp:attachment":[{"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hcdvillademerlo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}